{"id":10056997,"date":"2024-10-19T11:20:27","date_gmt":"2024-10-19T11:20:27","guid":{"rendered":"https:\/\/swn.af\/uz\/?p=10056997"},"modified":"2024-10-19T11:26:47","modified_gmt":"2024-10-19T11:26:47","slug":"ishbilarmon-ayollarning-qishloq-xojaligi-mahsulotlari-korgazmasini-otkazish-haqidagi-optimizmi-bizning-sotuvlarimiz-yaxshi","status":"publish","type":"post","link":"https:\/\/swn.af\/uz\/ishbilarmon-ayollarning-qishloq-xojaligi-mahsulotlari-korgazmasini-otkazish-haqidagi-optimizmi-bizning-sotuvlarimiz-yaxshi\/","title":{"rendered":"\u062a\u062f\u0628\u06cc\u0631\u06a9\u0627\u0631 \u0639\u06cc\u0627\u0644\u0644\u0631 \u0646\u06cc\u0646\u06af \u0627\u06cc\u06a9\u06cc\u0646\u0686\u06cc\u0644\u06cc\u06a9 \u0645\u062d\u0635\u0648\u0644\u0644\u0631\u06cc \u06a9\u0648\u0631\u06af\u0632\u0645\u0647\u200c\u0633\u06cc\u062f\u0646 \u0627\u0645\u06cc\u062f\u0648\u0627\u0631\u0644\u06cc\u06af\u06cc\u061b \u00ab\u06cc\u062e\u0634\u06cc \u0633\u0648\u062f\u0627 \u0642\u06cc\u0644\u062f\u06cc\u06a9\u00bb"},"content":{"rendered":"<p dir=\"rtl\"><strong>\u06a9\u0627\u0628\u0644 \u0634\u0647\u0631\u06cc \u0628\u0627\u062f\u0627\u0645\u200c\u200c\u0628\u0627\u063a\u06cc\u200c\u062f\u0647 \u06cc\u0648\u0644\u06af\u0647 \u0642\u0648\u06cc\u06cc\u0644\u06af\u0646 \u0627\u06cc\u0686\u06a9\u06cc \u062a\u0648\u0644\u06cc\u062f\u200c\u0644\u0631\u060c \u0686\u0627\u0631\u0648\u0647\u200c\u0686\u06cc\u0644\u06cc\u06a9 \u0648 \u0627\u06cc\u06a9\u06cc\u0646\u0686\u06cc\u0644\u06cc\u06a9 \u0645\u062d\u0635\u0648\u0644\u0627\u062a\u06cc \u0646\u06cc\u0646\u06af \u06f3\u06f1-\u06a9\u0648\u0631\u06af\u0632\u0645\u0647\u200c\u0633\u06cc\u062f\u0647\u200c \u062a\u062f\u0628\u06cc\u0631\u06a9\u0627\u0631 \u0639\u06cc\u0627\u0644\u200c\u0644\u0631\u062f\u0646 \u0642\u0637\u0627\u0631\u06cc \u0646\u06cc\u0646\u06af \u0627\u06cc\u062a\u06cc\u0634\u0644\u0631\u06cc\u0686\u0647\u060c \u06a9\u0648\u0631\u06af\u0632\u0645\u0647\u200c\u0644\u0631 \u0646\u06cc\u0646\u06af \u06cc\u0648\u0644\u06af\u0647 \u0642\u0648\u06cc\u06cc\u0644\u06cc\u0634\u06cc \u0627\u0648\u0644\u0631 \u06af\u0647 \u0628\u0627\u0632\u0627\u0631 \u062a\u0627\u067e\u06cc\u0634 \u0632\u0645\u06cc\u0646\u0647\u200c\u0633\u06cc\u0646\u06cc \u06cc\u0631\u0647\u200c\u062a\u06af\u0646 \u0648 \u0628\u0648 \u062a\u0648\u063a\u0631\u06cc\u062f\u0647 \u06a9\u0648\u067e\u0631\u0627\u0642 \u062a\u0648\u062c\u0647 \u0642\u0631\u0647\u200c\u062a\u06cc\u0644\u06cc\u0634\u06cc \u06a9\u06cc\u0631\u0647\u200c\u06a9. <\/strong><\/p>\n<p dir=\"rtl\">\u0645\u0630\u06a9\u0648\u0631 \u06a9\u0648\u0631\u06af\u0632\u0645\u0647\u200c\u062f\u0647 \u0642\u0648\u0644 \u0635\u0646\u0627\u0639\u062a\u06cc \u0646\u06cc \u0646\u0645\u0627\u06cc\u0634 \u06af\u0647 \u0642\u0648\u06cc\u06cc\u0628 \u0648 \u0633\u0627\u062a\u06cc\u0644\u06cc\u0634\u06cc\u0646\u06cc \u06a9\u0648\u062a\u06cc\u0628 \u062a\u0648\u0631\u06af\u0646 \u00ab\u0641\u0648\u0632\u06cc\u0647 \u062a\u06cc\u06a9\u0648\u0648\u0686\u06cc\u0644\u06cc\u06a9 \u0648 \u06af\u0644\u200c\u062f\u0648\u0632\u0644\u06cc\u06a9\u00bb \u0627\u06cc\u0634\u200c\u062e\u0627\u0646\u0647 \u0645\u0633\u0626\u0648\u0644\u06cc \u0641\u0648\u0632\u06cc\u0647 \u0633\u062e\u06cc\u200c\u0632\u0627\u062f\u0647 \u0627\u06cc\u062a\u06cc\u0634\u06cc\u0686\u0647\u060c \u0628\u0648 \u06a9\u0648\u0631\u06af\u0632\u0645\u0647 \u0646\u06cc\u0646\u06af \u06cc\u0648\u0644\u06af\u0647 \u0642\u0648\u06cc\u06cc\u0644\u06af\u0646\u06cc\u200c \u0648 \u0645\u062d\u0635\u0648\u0644\u0627\u062a\u06cc \u0633\u0627\u062a\u06cc\u0644\u06cc\u0634\u06cc \u062e\u0635\u0648\u0635\u06cc\u062f\u0647 \u0642\u0648\u0644\u06af\u0647 \u06a9\u06cc\u0644\u062a\u06cc\u0631\u06af\u0646 \u0641\u0631\u0635\u062a\u060c \u0627\u0648\u0646\u06cc\u0646\u06af \u0627\u0648\u0686\u0648\u0646 \u06a9\u0648\u067e \u0627\u0648\u0646\u0645\u0644\u06cc \u062f\u06cc\u0631. \u00ab\u06a9\u0648\u0631\u06af\u0632\u0645\u0647\u200c\u0644\u0631 \u062a\u0648\u0631\u0644\u06cc \u0646\u0647\u0627\u062f\u0644\u0631 \u0648 \u0645\u0627\u0644\u06cc \u062d\u0645\u0627\u06cc\u062a \u0642\u06cc\u0644\u0648\u0648\u0686\u06cc\u0644\u0631 \u0628\u06cc\u0644\u0646 \u062a\u0627\u0646\u06cc\u0634\u06cc\u0645\u06cc\u0632 \u0648 \u0634\u0648\u0646\u06cc\u0646\u06af\u062f\u06cc\u06a9 \u06a9\u0648\u067e\u06cc\u0646\u0686\u0647 \u0645\u0634\u062a\u0631\u06cc \u062a\u0627\u067e\u06cc\u0634\u06cc\u0645\u06cc\u0632 \u062e\u0635\u0648\u0635\u06cc\u062f\u0647 \u06cc\u0627\u0631\u062f\u0645 \u0628\u06cc\u0631\u0647\u200c\u062f\u06cc.\u00bb<\/p>\n<p dir=\"rtl\">\u00ab\u0627\u06a9\u062a\u06cc\u062f\u00bb \u0646\u0647\u0627\u062f\u06cc \u062d\u0645\u0627\u06cc\u062a\u06cc \u0628\u06cc\u0644\u0646 \u0628\u062f\u062e\u0634\u0627\u0646 \u062f\u0646 \u0628\u0648 \u06cc\u06cc\u0631\u06af\u0647 \u06a9\u06cc\u0644\u06af\u0646 \u0641\u0648\u0632\u06cc\u0647 \u0646\u06cc\u0646\u06af \u06a9\u0648\u067e\u0647\u200c\u06cc\u062a\u06cc\u0631\u06cc\u0634\u06cc\u0686\u0647\u060c \u0645\u0630\u06a9\u0648\u0631 \u0627\u06cc\u0634\u200c\u062e\u0627\u0646\u0647\u200c\u062f\u0647 \u062a\u06cc\u06a9\u0648\u0648\u0686\u06cc\u0644\u06cc\u06a9\u060c\u06af\u0644\u200c\u062f\u0648\u0632\u0644\u06cc\u06a9\u060c \u0645\u0647\u0631\u0647\u200c\u062f\u0648\u0632\u0644\u06cc\u06a9 \u0648 \u06cc\u0648\u0646\u06af \u06cc\u06cc\u06af\u06cc\u0631\u06cc\u0634 \u0628\u0648\u0644\u06cc\u0645\u06cc\u200c\u062f\u0647\u060c \u06f5\u06f0 \u0639\u06cc\u0627\u0644 \u06af\u0647 \u0627\u06cc\u0634 \u0632\u0645\u06cc\u0646\u0647\u200c\u0633\u06cc \u0646\u06cc \u06cc\u0631\u0647\u200c\u062a\u06af\u0646.<\/p>\n<p dir=\"rtl\">\u0628\u0627\u062f\u0627\u0645\u200c\u0628\u0627\u063a\u200c\u200c\u062f\u0647 \u0627\u06cc\u06a9\u06cc\u0646\u0686\u06cc\u0644\u06cc\u06a9 \u0648 \u0642\u0648\u0644 \u0635\u0646\u0627\u0639\u062a\u06cc \u062e\u0635\u0648\u0635\u06cc\u062f\u0647\u200c\u06af\u06cc \u062a\u062f\u0628\u06cc\u0631\u06a9\u0627\u0631 \u0639\u06cc\u0627\u0644\u0644\u0631\u062f\u0646 \u0628\u0627\u0634\u0642\u0647 \u0628\u06cc\u0631\u06cc \u0622\u0646\u06cc\u062a\u0627 \u0633\u062e\u06cc\u200c\u0632\u0627\u062f\u0647 \u0646\u06cc\u0646\u06af \u0627\u06cc\u062a\u06cc\u0634\u06cc\u0686\u0647: \u00ab\u0628\u06cc\u0631\u06cc\u0646\u0686\u06cc \u0645\u0631\u062a\u0647 \u062f\u06cc\u0631 \u06a9\u0647 \u0627\u06a9\u062a\u06cc\u062f \u062f\u0641\u062a\u0631\u06cc \u062d\u0645\u0627\u06cc\u062a\u06cc \u0628\u06cc\u0644\u0646 \u0647\u0631\u0627\u062a \u062f\u0646 \u0628\u0648 \u06a9\u0648\u0631\u06af\u0632\u0645\u0647 \u06af\u0647 \u0634\u0631\u06a9\u062a \u0642\u06cc\u0644\u06af\u0646\u200c\u0645\u06cc\u0646\u061b \u06a9\u0648\u067e \u062e\u0648\u0631\u0633\u0646\u062f\u200c\u0645\u06cc\u0646\u061b \u0639\u06cc\u0627\u0644\u0644\u0631 \u0646\u06cc\u0646\u06af \u062d\u0645\u0627\u06cc\u062a \u0642\u06cc\u0644\u0647\u200c\u062f\u06cc\u06af\u0646 \u0646\u0647\u0627\u062f\u0644\u0631\u062f\u0646 \u0639\u06cc\u0627\u0644\u0644\u0631 \u0646\u06cc\u0646\u06af \u06a9\u0648\u067e\u0631\u0627\u0642 \u062d\u0645\u0627\u06cc\u062a \u0642\u06cc\u0644\u06cc\u0646\u06cc\u0634\u06cc\u0646\u06cc \u0627\u06cc\u0633\u062a\u0647\u200c\u06cc\u0645\u06cc\u0632 \u06a9\u0647 \u0627\u0648\u0632\u0644\u0631\u06cc \u0645\u0633\u062a\u0642\u0644 \u0628\u0648\u0644\u0633\u06cc\u0646\u0644\u0631.\u00bb<\/p>\n<p dir=\"rtl\"><span style=\"color: #3366ff\"><strong><a style=\"color: #3366ff\" href=\"https:\/\/twitter.com\/SW_Uzbek\">\u0628\u06cc\u0632\u0644\u0631\u0646\u06cc\u0646\u06af \u00ab\u0627\u06cc\u06a9\u0633\u00bb \u062a\u0631\u0645\u0627\u063a\u06cc \u062f\u0647 \u0647\u0645 \u062a\u0639\u0642\u06cc\u0628 \u0642\u06cc\u0644\u06cc\u0646\u06af!<\/a><\/strong><\/span><\/p>\n<p dir=\"rtl\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-10057004 aligncenter\" src=\"https:\/\/swn.af\/uz\/wp-content\/uploads\/2024\/10\/Merchant-women-at-the-exhibition-1.jpg\" alt=\"\" width=\"900\" height=\"600\" srcset=\"https:\/\/swn.af\/uz\/wp-content\/uploads\/2024\/10\/Merchant-women-at-the-exhibition-1.jpg 900w, https:\/\/swn.af\/uz\/wp-content\/uploads\/2024\/10\/Merchant-women-at-the-exhibition-1-300x200.jpg 300w, https:\/\/swn.af\/uz\/wp-content\/uploads\/2024\/10\/Merchant-women-at-the-exhibition-1-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<p dir=\"rtl\">\u0627\u0648\u060c \u0633\u0631\u067e\u0631\u0633\u062a \u062d\u06a9\u0648\u0645\u062a \u0648 \u06cc\u0627\u0631\u062f\u0645 \u0628\u06cc\u0631\u0648\u0648\u0686\u06cc \u0646\u0647\u0627\u062f\u0644\u0631\u062f\u0646\u060c \u06a9\u0648\u0631\u06af\u0632\u0645\u0647\u200c\u0644\u0631 \u06af\u0647 \u062a\u062f\u0628\u06cc\u0631\u06a9\u0627\u0631 \u0639\u06cc\u0627\u0644\u0644\u0631 \u0627\u0634\u062a\u0631\u0627\u06a9 \u0642\u06cc\u0644\u06cc\u0634\u0644\u0631\u06cc \u0632\u0645\u06cc\u0646\u0647\u200c\u0633\u06cc \u0646\u06cc\u0646\u06af \u06a9\u0648\u067e\u0647\u200c\u06cc\u062a\u06cc\u0631\u06cc\u0644\u06cc\u0634\u06cc\u0646\u06cc \u0627\u06cc\u0633\u062a\u0647\u200c\u06af\u0646.<\/p>\n<p dir=\"rtl\">\u0642\u0648\u0644 \u0635\u0646\u0627\u0639\u062a\u06cc \u0628\u0648\u0644\u06cc\u0645\u06cc\u200c\u062f\u0647 \u0641\u0639\u0627\u0644\u06cc\u062a \u0642\u06cc\u0644\u0647\u200c\u062f\u06cc\u06af\u0646 \u06f5\u06f8 \u06cc\u0627\u0634\u0631 \u062d\u0628\u06cc\u0628\u0647 \u0633\u0627\u062f\u0627\u062a \u0646\u06cc\u0646\u06af \u0627\u06cc\u062a\u06cc\u0634\u06cc\u0686\u0647\u060c \u0627\u0648\u0634\u0628\u0648 \u06a9\u0648\u0631\u06af\u0632\u0645\u0647\u200c\u0644\u0631\u062f\u0647 \u0642\u0631\u0635\u060c \u06cc\u0642\u0647\u060c \u0628\u06cc\u06a9 \u0648 \u0647\u0632\u0627\u0631\u06af\u06cc \u06a9\u06cc\u06cc\u0645\u200c\u0644\u0631 \u062a\u0648\u063a\u0631\u06cc\u0633\u06cc\u062f\u0647 \u0646\u06cc\u0686\u0647 \u0642\u0631\u0627\u0631\u062f\u0627\u062f \u0646\u06cc \u0642\u0648\u0644\u06af\u0647 \u06a9\u06cc\u0644\u062a\u06cc\u0631\u0647 \u0622\u0644\u06af\u0646.<\/p>\n<p dir=\"rtl\">\u00ab\u0622\u0646\u06af\u0628\u06cc\u0646\u00bb \u0634\u0631\u06a9\u062a \u0645\u0633\u0626\u0648\u0644\u06cc \u0648 \u06a9\u0627\u0628\u0644 \u0634\u0647\u0631\u06cc \u0628\u0627\u062f\u0627\u0645\u200c\u0628\u0627\u063a\u06cc\u200c\u062f\u0647 \u06cc\u0648\u0644\u06af\u0647 \u0642\u0648\u06cc\u06cc\u0644\u06af\u0646 \u0627\u06cc\u0686\u06a9\u06cc \u062a\u0648\u0644\u06cc\u062f\u200c\u0644\u0631\u060c \u0686\u0627\u0631\u0648\u0647\u200c\u0686\u06cc\u0644\u06cc\u06a9 \u0648 \u0627\u06cc\u06a9\u06cc\u0646\u0686\u06cc\u0644\u06cc\u06a9 \u0645\u062d\u0635\u0648\u0644\u0627\u062a\u06cc \u0646\u06cc\u0646\u06af \u06f3\u06f1-\u06a9\u0648\u0631\u06af\u0632\u0645\u0647\u200c\u0633\u06cc \u06af\u0647 \u0634\u0631\u06a9\u062a \u0642\u06cc\u0644\u06af\u0646 \u0645\u0633\u0639\u0648\u062f\u0647 \u0639\u062b\u0645\u0627\u0646\u06cc \u0646\u06cc\u0646\u06af \u0627\u06cc\u062a\u06cc\u0634\u06cc\u0686\u0647: \u00ab\u06a9\u0648\u0631\u06af\u0632\u0645\u0647\u200c\u0644\u0631 \u06af\u0647 \u0634\u0631\u06a9\u062a \u0642\u06cc\u0644\u06cc\u0634 \u0641\u0627\u06cc\u062f\u0647\u200c\u0644\u06cc \u062f\u06cc. \u06a9\u0648\u0631\u06af\u0632\u0645\u0647\u200c\u0644\u0631 \u0646\u06cc\u0646\u06af \u06cc\u0648\u0644\u06af\u0647 \u0642\u0648\u06cc\u06cc\u0644\u06cc\u0634\u06cc \u0628\u06cc\u0644\u0646 \u0627\u0647\u0627\u0644\u06cc \u0627\u0648\u0632 \u0627\u0648\u0644\u06a9\u0647\u200c\u0644\u0631\u06cc \u0645\u062d\u0635\u0648\u0644\u0627\u062a\u06cc \u062e\u0635\u0648\u0635\u06cc\u062f\u0647\u200c\u06af\u06cc \u0622\u06af\u0627\u0647\u06cc\u200c\u0644\u06cc\u06a9 \u062a\u0627\u067e\u0647\u200c\u062f\u06cc \u0648 \u0634\u0648\u0646\u06cc\u0646\u06af\u062f\u06cc\u06a9 \u0645\u062d\u0635\u0648\u0644\u0644\u0631\u06cc\u200c\u0645\u06cc\u0632 \u06af\u0647 \u0628\u0627\u0632\u0627\u0631 \u062a\u0627\u067e\u06cc\u0644\u06cc\u0634\u06cc \u0648 \u0633\u0627\u062a\u06cc\u0644\u06cc\u0634\u06cc \u0627\u0648\u0686\u0648\u0646 \u06cc\u062e\u0634\u06cc \u062f\u06cc\u0631.\u00bb<\/p>\n<p dir=\"rtl\">\u00ab\u062a\u0644\u0627\u0634\u00bb \u0642\u0648\u0644 \u0635\u0646\u0627\u0639\u062a\u06cc \u0648 \u062a\u06cc\u06a9\u0648\u0648\u0686\u06cc\u0644\u06cc\u06a9 \u0645\u0633\u0626\u0648\u0644\u06cc \u062e\u0627\u0637\u0631\u0647 \u0646\u0648\u0631\u06cc \u0646\u06cc\u0646\u06af \u0627\u06cc\u062a\u06cc\u0634\u06cc\u0686\u0647\u060c \u0634\u062e\u0635\u06cc \u0634\u06a9\u0644\u062f\u0647 \u0627\u06cc\u06a9\u06cc\u0646\u0686\u06cc\u0644\u06cc\u06a9\u060c \u0633\u0648\u0648\u063a\u0627\u0631\u06cc\u0634 \u0648 \u0686\u0627\u0631\u0648\u0647\u200c\u0686\u06cc\u0644\u06cc\u06a9 \u0648\u0632\u06cc\u0631\u0644\u06cc\u06af\u06cc\u200c\u062f\u0646 \u063a\u0631\u0641\u0647 \u0622\u0644\u06cc\u0628 \u0648 \u0628\u0648 \u06a9\u0648\u0631\u06af\u0632\u0645\u0647 \u06af\u0647 \u0634\u0631\u06a9\u062a \u0642\u06cc\u0644\u06af\u0646. \u00ab\u06a9\u0648\u0631\u06af\u0632\u0645\u0647 \u06af\u0647 \u0634\u0631\u06a9\u062a \u0642\u06cc\u0644\u06af\u0646\u06cc\u0645\u200c\u062f\u0646 \u0631\u0636\u0627\u06cc\u062a\u06cc\u0645 \u0628\u0627\u0631\u061b \u0634\u0631\u06a9\u062a \u0642\u06cc\u0644\u06af\u0646\u06cc\u0645 \u0633\u0648\u062f\u0627\u06af\u0631 \u0639\u06cc\u0627\u0644\u0644\u0631 \u0646\u06cc\u0646\u06af \u06a9\u0648\u0631\u06cc\u0634\u06cc\u0645 \u06af\u0647 \u0633\u0628\u0628 \u0628\u0648\u0644\u06af\u0646\u060c \u0627\u0647\u0627\u0644\u06cc \u062d\u0636\u0648\u0631\u06cc \u06a9\u0648\u067e \u0648 \u0633\u0627\u062a\u06cc\u0634\u0644\u0631\u06cc\u0645\u06cc\u0632 \u06cc\u062e\u0634\u06cc \u062f\u06cc\u0631.\u00bb<\/p>\n<p dir=\"rtl\">\u062e\u0627\u0637\u0631\u0647 \u0646\u06cc\u0646\u06af \u06a9\u0648\u067e\u0647\u200c\u06cc\u062a\u06cc\u0631\u06cc\u0634\u06cc\u0686\u0647\u060c \u0627\u06cc\u0634\u200c\u062e\u0627\u0646\u0647\u200c\u0633\u06cc\u062f\u0647 \u06f1\u06f1 \u06a9\u06cc\u0634\u06cc \u0627\u06cc\u0634 \u0628\u06cc\u0644\u0646 \u0634\u063a\u0644\u0644\u0646\u06cc\u0628 \u0648 \u0642\u0648\u0644 \u0635\u0646\u0627\u0639\u062a\u06cc\u060c \u062a\u0648\u0642\u0648\u0648\u0686\u06cc\u0644\u06cc\u06a9 \u0627\u0648\u0633\u06a9\u0648\u0646\u0647\u200c\u0644\u0631\u06cc\u060c \u0627\u0641\u063a\u0627\u0646\u06cc \u06a9\u06cc\u06cc\u0645\u200c\u0644\u0631 \u0648 \u0628\u06cc\u06a9 \u06a9\u0628\u06cc \u0645\u062d\u0635\u0648\u0644\u0644\u0631 \u062a\u0648\u0644\u06cc\u062f \u0642\u06cc\u0644\u0647\u200c\u062f\u06cc. \u00ab\u06a9\u0648\u067e\u06cc\u0646\u0686\u0647 \u0645\u062d\u0635\u0648\u0644\u0644\u0631 \u0646\u06cc \u062a\u0648\u0644\u06cc\u062f \u0642\u06cc\u0644\u06cc\u0628 \u0648 \u0633\u0627\u062a\u06cc\u0634 \u0627\u0648\u0686\u0648\u0646 \u0646\u0647\u0627\u062f\u0644\u0631\u062f\u0646 \u06a9\u06cc\u0644\u06cc\u0628 \u0648 \u0628\u06cc\u0632\u0644\u0631\u0646\u06cc \u062d\u0645\u0627\u06cc\u062a \u0642\u06cc\u0644\u06cc\u0634\u0644\u0631\u06cc\u0646\u06cc \u0627\u06cc\u0633\u062a\u0647\u200c\u06cc\u0645\u06cc\u0632\u00bb<\/p>\n<p dir=\"rtl\"><span style=\"color: #3366ff\"><strong><a style=\"color: #3366ff\" href=\"https:\/\/www.facebook.com\/swn.uzbek\">\u0628\u06cc\u0632\u0644\u0631\u0646\u06cc\u0646\u06af \u0641\u06cc\u0633\u0628\u0648\u06a9 \u0635\u062d\u06cc\u0641\u0647\u200c\u0645\u06cc\u0632\u06af\u0647 \u0628\u0627\u0634 \u0627\u0648\u0631\u06cc\u0646\u06af!<\/a><\/strong><\/span><\/p>\n<p dir=\"rtl\"><img decoding=\"async\" class=\"size-full wp-image-10057002 aligncenter\" src=\"https:\/\/swn.af\/uz\/wp-content\/uploads\/2024\/10\/Merchant-women-at-the-exhibition-12.jpg\" alt=\"\" width=\"900\" height=\"600\" srcset=\"https:\/\/swn.af\/uz\/wp-content\/uploads\/2024\/10\/Merchant-women-at-the-exhibition-12.jpg 900w, https:\/\/swn.af\/uz\/wp-content\/uploads\/2024\/10\/Merchant-women-at-the-exhibition-12-300x200.jpg 300w, https:\/\/swn.af\/uz\/wp-content\/uploads\/2024\/10\/Merchant-women-at-the-exhibition-12-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<p dir=\"rtl\">\u00ab\u0631\u0648\u067e\u0627\u0646\u06cc\u00bb \u0634\u0631\u06a9\u062a\u06cc \u0627\u06cc\u0634\u0644\u0627\u0648\u0686\u06cc\u0644\u0631\u06cc\u062f\u0646 \u06f2\u06f0 \u06cc\u0627\u0634\u0631 \u0633\u0648\u06cc\u062a\u0627 \u0646\u06cc\u0646\u06af \u0627\u06cc\u062a\u06cc\u0634\u06cc\u0686\u0647\u060c \u0645\u0630\u06a9\u0648\u0631 \u0634\u0631\u06a9\u062a\u200c\u062f\u0647 \u0632\u0631\u06af\u0631\u0644\u06cc\u06a9 \u0648 \u0627\u0648\u06cc\u0645\u0647\u200c\u06a9\u0627\u0631\u0644\u06cc\u06a9 \u0628\u0648\u0644\u06cc\u0645\u200c\u0644\u0631\u06cc\u062f\u0647 \u06f6\u06f0 \u06a9\u06cc\u0634\u06cc \u0627\u06cc\u0634 \u0628\u06cc\u0644\u0646 \u0634\u063a\u0644\u0644\u0646\u06af\u0646. \u0627\u0648\u0646\u06cc\u0646\u06af \u06a9\u0648\u067e\u0647\u200c\u06cc\u062a\u06cc\u0631\u06cc\u0634\u06cc\u0686\u0647: \u00ab\u0647\u0631 \u0628\u06cc\u0631 \u0635\u0646\u0641\u200c\u062f\u0647 \u06f1\u06f0-\u06f2\u06f0 \u06a9\u06cc\u0634\u06cc \u0632\u0631\u06af\u0631\u0644\u06cc\u06a9\u060c \u0627\u0648\u06cc\u0645\u0647\u200c\u06a9\u0627\u0631\u0644\u06cc\u06a9 \u0648 \u0633\u0646\u06af\u200c\u062a\u0631\u0627\u0634\u0644\u06cc\u06a9 \u0628\u0648\u0644\u06cc\u0645\u200c\u0644\u0631\u06cc\u062f\u0647 \u0627\u06cc\u0634\u0644\u0647\u200c\u06cc\u062f\u06cc\u0631. \u0628\u0648 \u06a9\u0648\u0631\u06af\u0632\u0645\u0647 \u06af\u0647 \u0634\u0631\u06a9\u062a \u0642\u06cc\u0644\u06af\u0646\u06cc\u0645\u200c\u062f\u0646 \u06a9\u0648\u067e \u062e\u0648\u0634\u200c\u0645\u06cc\u0646. \u0633\u0648\u0646\u06af\u06cc \u06a9\u0648\u0646\u0644\u0631 \u0645\u062d\u0635\u0648\u0644\u0644\u0631\u06cc\u0645\u06cc\u0632 \u0646\u06cc\u0646\u06af \u0633\u0627\u062a\u06cc\u0644\u06cc\u0634\u06cc \u06cc\u062e\u0634\u06cc \u0648 \u06a9\u0648\u0631\u06cc\u0628 \u0686\u06cc\u0642\u0642\u0647\u200c\u062f\u06cc\u06af\u0646\u0644\u0631 \u0633\u0627\u0646\u06cc \u0647\u0645 \u06a9\u0648\u067e \u062f\u06cc\u0631.\u00bb<\/p>\n<p dir=\"rtl\">\u0627\u06cc\u06a9\u06cc \u06cc\u06cc\u0644 \u0622\u0644\u062f\u06cc\u0646 \u0642\u0648\u0644 \u0635\u0646\u0627\u0639\u062a\u06cc \u0634\u0631\u06a9\u062a\u06cc \u0646\u06cc \u0627\u06cc\u062c\u0627\u062f \u0642\u06cc\u0644\u06cc\u0628 \u0648 \u06f1\u06f6 \u06a9\u06cc\u0634\u06cc \u06af\u0647 \u0627\u06cc\u0634 \u0632\u0645\u06cc\u0646\u0647\u200c\u200c\u0633\u06cc\u0646\u06cc \u06cc\u0631\u0647\u200c\u062a\u06af\u0646 \u062f\u06cc\u0627\u0646\u0627 \u0646\u06cc\u0646\u06af \u0627\u06cc\u062a\u06cc\u0634\u06cc\u0686\u0647\u060c \u0634\u0631\u06a9\u062a\u06cc\u200c\u062f\u0647 \u0627\u0641\u063a\u0627\u0646\u06cc \u06a9\u06cc\u06cc\u0645\u200c\u0644\u0631\u060c \u0645\u0647\u0631\u0647 \u062a\u06cc\u06a9\u06cc\u0644\u06af\u0646 \u0628\u06cc\u06a9\u200c\u0644\u0631 \u0648 \u0628\u0627\u0634\u0642\u0647 \u0642\u0648\u0644 \u0635\u0646\u0627\u0639\u062a\u06cc \u062a\u0648\u0644\u06cc\u062f \u0648 \u0627\u06cc\u0686\u06a9\u06cc \u0648 \u062a\u0634\u0642\u06cc \u0628\u0627\u0632\u0627\u0631\u0644\u0631 \u06af\u0647 \u0639\u0631\u0636\u0647 \u0628\u0648\u0644\u0647\u200c\u062f\u06cc. \u0627\u0648\u0646\u06cc\u0646\u06af \u06a9\u0648\u067e\u0647\u200c\u06cc\u062a\u06cc\u0631\u06cc\u0634\u06cc\u0686\u0647: \u00ab\u06a9\u0648\u0631\u06af\u0632\u0645\u0647 \u0641\u0631\u0647\u0646\u06af\u06cc\u200c\u0645\u06cc\u0632 \u0646\u06cc \u06a9\u0648\u0631\u0633\u062a\u0647\u200c\u062f\u06cc\u061b \u06a9\u0648\u0631\u06af\u0632\u0645\u0647 \u0639\u06cc\u0627\u0644\u0644\u0631 \u0646\u06cc\u0646\u06af \u0631\u0627\u062d\u062a \u0628\u06cc\u0631 \u0634\u06a9\u0644\u062f\u0647 \u0627\u06cc\u0634\u0644\u0634\u06cc \u0648 \u0645\u062d\u0635\u0648\u0644\u0644\u0631\u06cc \u0646\u06cc\u0646\u06af \u0633\u0627\u062a\u06cc\u0634\u0644\u0631\u06cc \u0627\u0648\u0686\u0648\u0646 \u06cc\u06af\u0627\u0646\u0647 \u0628\u0648\u0644\u06cc\u0645 \u062f\u06cc\u0631. \u0627\u0647\u0627\u0644\u06cc \u0648 \u0646\u0647\u0627\u062f\u0644\u0631 \u06a9\u0648\u0631\u06af\u0632\u0645\u0647\u200c\u0644\u0631 \u06af\u0647 \u0628\u0627\u0631\u06cc\u0628 \u0648 \u0645\u062d\u0635\u0648\u0644\u0644\u0631\u06cc\u0645\u06cc\u0632 \u06af\u0647 \u0628\u0627\u0632\u0627\u0631 \u062a\u0627\u067e\u06cc\u0644\u0647\u200c\u062f\u06cc.\u00bb<\/p>\n<p dir=\"rtl\">\u0627\u06cc\u062a\u06cc\u0634 \u06a9\u06cc\u0631\u0647\u200c\u06a9 \u06a9\u0647\u060c \u0645\u0630\u06a9\u0648\u0631 \u06a9\u0648\u0631\u06af\u0632\u0645\u0647\u200c\u062f\u0647 \u0627\u0641\u063a\u0627\u0646\u0633\u062a\u0627\u0646 \u0646\u06cc\u0646\u06af \u0627\u06cc\u06a9\u06cc\u0646\u0686\u06cc\u0644\u06cc\u06a9 \u0648 \u0686\u0627\u0631\u0648\u0647\u200c\u0686\u06cc\u0644\u06cc\u06a9 \u0645\u062d\u0635\u0648\u0644\u0627\u062a\u06cc\u060c \u067e\u0631\u0648\u0633\u0633 \u0628\u0648\u0644\u06af\u0646 \u062a\u0648\u0644\u06cc\u062f\u0644\u0631\u060c \u0642\u0648\u0644 \u0635\u0646\u0627\u0639\u062a\u06cc\u060c \u0627\u06cc\u06a9\u06cc\u0646\u0686\u06cc\u0644\u06cc\u06a9 \u0645\u0627\u0634\u06cc\u0646\u200c\u0644\u0631 \u0648 \u0627\u06cc\u0686\u06a9\u06cc \u062a\u0648\u0644\u06cc\u062f\u0644\u0631 \u062f\u0633\u062a\u06af\u0627\u0647\u200c\u0644\u0631\u06cc \u0646\u0645\u0627\u06cc\u0634 \u06af\u0647 \u0642\u0648\u06cc\u06cc\u0644\u06af\u0646. \u0633\u0631\u067e\u0631\u0633\u062a \u062d\u06a9\u0648\u0645\u062a \u0646\u06cc\u0646\u06af \u0627\u06cc\u06a9\u06cc\u0646\u0686\u06cc\u0644\u06cc\u06a9\u060c \u0633\u0648\u0648\u063a\u0627\u0631\u06cc\u0634 \u0648 \u0686\u0627\u0631\u0648\u0647\u200c\u0686\u06cc\u0644\u06cc\u06a9 \u0648\u0632\u06cc\u0631\u0644\u06cc\u06af\u06cc \u0646\u06cc\u0646\u06af \u0627\u0639\u0644\u0627\u0645\u06cc\u0647\u200c\u0633\u06cc \u0627\u0633\u0627\u0633\u06cc\u062f\u0647\u060c \u06a9\u0627\u0628\u0644 \u0634\u0647\u0631\u06cc \u0628\u0627\u062f\u0627\u0645\u200c\u200c\u0628\u0627\u063a\u06cc\u200c\u062f\u0647 \u06cc\u0648\u0644\u06af\u0647 \u0642\u0648\u06cc\u06cc\u0644\u06af\u0646 \u0627\u06cc\u0686\u06a9\u06cc \u062a\u0648\u0644\u06cc\u062f\u200c\u0644\u0631\u060c \u0686\u0627\u0631\u0648\u0647\u200c\u0686\u06cc\u0644\u06cc\u06a9 \u0648 \u0627\u06cc\u06a9\u06cc\u0646\u0686\u06cc\u0644\u06cc\u06a9 \u0645\u062d\u0635\u0648\u0644\u0627\u062a\u06cc \u0646\u06cc\u0646\u06af \u06f3\u06f1-\u06a9\u0648\u0631\u06af\u0632\u0645\u0647\u200c\u0633\u06cc\u062f\u0647\u200c\u060c \u06f2\u06f6\u06f3 \u063a\u0631\u0641\u0647 \u0646\u0645\u0627\u06cc\u0634 \u06af\u0647 \u0642\u0648\u06cc\u06cc\u0644\u06af\u0646 \u06a9\u0647\u060c \u06f5\u06f6 \u063a\u0631\u0641\u0647 \u0639\u06cc\u0627\u0644\u0644\u0631 \u06af\u0647 \u0627\u062e\u062a\u0635\u0627\u0635 \u0628\u06cc\u0631\u06cc\u0644\u06af\u0646.<\/p>\n<p dir=\"rtl\">\u06a9\u0627\u0628\u0644 \u0634\u0647\u0631\u06cc \u0628\u0627\u062f\u0627\u0645\u200c\u200c\u0628\u0627\u063a\u06cc\u200c\u062f\u0647 \u06cc\u0648\u0644\u06af\u0647 \u0642\u0648\u06cc\u06cc\u0644\u06af\u0646 \u0627\u06cc\u0686\u06a9\u06cc \u062a\u0648\u0644\u06cc\u062f\u200c\u0644\u0631\u060c \u0686\u0627\u0631\u0648\u0647\u200c\u0686\u06cc\u0644\u06cc\u06a9 \u0648 \u0627\u06cc\u06a9\u06cc\u0646\u0686\u06cc\u0644\u06cc\u06a9 \u0645\u062d\u0635\u0648\u0644\u0627\u062a\u06cc \u0646\u06cc\u0646\u06af \u06f3\u06f1-\u06a9\u0648\u0631\u06af\u0632\u0645\u0647\u200c\u0633\u06cc\u060c \u0627\u0648\u062a\u06af\u0646 \u0647\u0641\u062a\u0647 \u0686\u0647\u0627\u0631\u0634\u0646\u0628\u0647 \u06a9\u0648\u0646\u06cc \u0633\u0631\u067e\u0631\u0633\u062a \u062d\u06a9\u0648\u0645\u062a \u0646\u06cc\u0646\u06af \u06cc\u0648\u0642\u0627\u0631\u06cc \u0645\u0631\u062a\u0628\u0647\u200c\u0644\u06cc \u0631\u0633\u0645\u06cc\u200c\u0644\u0631\u06cc \u062c\u0645\u0644\u0647\u200c\u200c\u062f\u0646 \u0627\u0633\u0644\u0627\u0645 \u0627\u0645\u06cc\u0631\u0644\u06cc\u06af\u06cc \u0628\u0627\u0634 \u0648\u0632\u06cc\u0631\u06cc \u0646\u06cc\u0646\u06af \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0627\u0648\u0631\u06cc\u0646 \u0628\u0627\u0633\u0631\u06cc \u0639\u0628\u062f\u0627\u0644\u063a\u0646\u06cc \u0628\u0631\u0627\u062f\u0631\u060c \u0627\u06cc\u06a9\u06cc\u0646\u0686\u06cc\u0644\u06cc\u06a9\u060c \u0633\u0648\u0648\u063a\u0627\u0631\u06cc\u0634 \u0648 \u0686\u0627\u0631\u0648\u0647\u200c\u0686\u06cc\u0644\u06cc\u06a9 \u0648\u0632\u06cc\u0631\u0644\u06cc\u06af\u06cc \u0645\u0633\u0626\u0648\u0644\u0644\u0631\u06cc \u0648 \u0628\u0627\u0634\u0642\u0647 \u0645\u0644\u06cc \u0648 \u062e\u0644\u0642\u200c\u0627\u0631\u0627 \u0646\u0647\u0627\u062f\u0644\u0631 \u0645\u0633\u0626\u0648\u0644\u0644\u0631\u06cc \u0646\u06cc\u0646\u06af \u062d\u0636\u0648\u0631\u06cc \u0628\u06cc\u0644\u0646 \u06a9\u0627\u0628\u0644 \u062f\u0647 \u0622\u0686\u06cc\u0644\u06af\u0646.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u06a9\u0627\u0628\u0644 \u0634\u0647\u0631\u06cc \u0628\u0627\u062f\u0627\u0645\u200c\u200c\u0628\u0627\u063a\u06cc\u200c\u062f\u0647 \u06cc\u0648\u0644\u06af\u0647 \u0642\u0648\u06cc\u06cc\u0644\u06af\u0646 \u0627\u06cc\u0686\u06a9\u06cc \u062a\u0648\u0644\u06cc\u062f\u200c\u0644\u0631\u060c \u0686\u0627\u0631\u0648\u0647\u200c\u0686\u06cc\u0644\u06cc\u06a9 \u0648 \u0627\u06cc\u06a9\u06cc\u0646\u0686\u06cc\u0644\u06cc\u06a9 \u0645\u062d\u0635\u0648\u0644\u0627\u062a\u06cc \u0646\u06cc\u0646\u06af \u06f3\u06f1-\u06a9\u0648\u0631\u06af\u0632\u0645\u0647\u200c\u0633\u06cc\u062f\u0647\u200c \u062a\u062f\u0628\u06cc\u0631\u06a9\u0627\u0631 \u0639\u06cc\u0627\u0644\u200c\u0644\u0631\u062f\u0646 \u0642\u0637\u0627\u0631\u06cc \u0646\u06cc\u0646\u06af \u0627\u06cc\u062a\u06cc\u0634\u0644\u0631\u06cc\u0686\u0647\u060c \u06a9\u0648\u0631\u06af\u0632\u0645\u0647\u200c\u0644\u0631 \u0646\u06cc\u0646\u06af \u06cc\u0648\u0644\u06af\u0647 \u0642\u0648\u06cc\u06cc\u0644\u06cc\u0634\u06cc \u0627\u0648\u0644\u0631 \u06af\u0647 \u0628\u0627\u0632\u0627\u0631 \u062a\u0627\u067e\u06cc\u0634 \u0632\u0645\u06cc\u0646\u0647\u200c\u0633\u06cc\u0646\u06cc \u06cc\u0631\u0647\u200c\u062a\u06af\u0646 \u0648 \u0628\u0648 \u062a\u0648\u063a\u0631\u06cc\u062f\u0647 \u06a9\u0648\u067e\u0631\u0627\u0642 \u062a\u0648\u062c\u0647 \u0642\u0631\u0647\u200c\u062a\u06cc\u0644\u06cc\u0634\u06cc \u06a9\u06cc\u0631\u0647\u200c\u06a9.<\/p>\n","protected":false},"author":7,"featured_media":10057003,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[197,136,114,116],"tags":[10350,5099,5557,155,2970],"class_list":["post-10056997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-society","category-afghanistan","category-news","category-news-reports","tag-10350","tag-5099","tag-5557","tag-155","tag-2970"],"acf":[],"_links":{"self":[{"href":"https:\/\/swn.af\/uz\/wp-json\/wp\/v2\/posts\/10056997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swn.af\/uz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swn.af\/uz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swn.af\/uz\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/swn.af\/uz\/wp-json\/wp\/v2\/comments?post=10056997"}],"version-history":[{"count":4,"href":"https:\/\/swn.af\/uz\/wp-json\/wp\/v2\/posts\/10056997\/revisions"}],"predecessor-version":[{"id":10057010,"href":"https:\/\/swn.af\/uz\/wp-json\/wp\/v2\/posts\/10056997\/revisions\/10057010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swn.af\/uz\/wp-json\/wp\/v2\/media\/10057003"}],"wp:attachment":[{"href":"https:\/\/swn.af\/uz\/wp-json\/wp\/v2\/media?parent=10056997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swn.af\/uz\/wp-json\/wp\/v2\/categories?post=10056997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swn.af\/uz\/wp-json\/wp\/v2\/tags?post=10056997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}