{"id":37267,"date":"2020-05-24T04:02:08","date_gmt":"2020-05-24T04:02:08","guid":{"rendered":"https:\/\/swn.af\/lib\/?p=37267"},"modified":"2020-12-18T08:16:08","modified_gmt":"2020-12-18T08:16:08","slug":"%d8%af-%d8%a8%da%ab%d8%b1%d8%a7%d9%85-%d9%be%d8%b1-%d9%86%d8%b8%d8%a7%d9%85%d9%8a-%d9%87%d9%88%d8%a7%d9%8a%d9%8a-%da%89%da%ab%d8%b1-%d8%b1%d8%a7%da%a9%db%90%d9%bc%d9%8a-%d8%a8%d8%b1%db%8c%d8%af%d9%88","status":"publish","type":"post","link":"https:\/\/swn.af\/archive\/%d8%af-%d8%a8%da%ab%d8%b1%d8%a7%d9%85-%d9%be%d8%b1-%d9%86%d8%b8%d8%a7%d9%85%d9%8a-%d9%87%d9%88%d8%a7%d9%8a%d9%8a-%da%89%da%ab%d8%b1-%d8%b1%d8%a7%da%a9%db%90%d9%bc%d9%8a-%d8%a8%d8%b1%db%8c%d8%af%d9%88\/","title":{"rendered":"\u062f \u0628\u06ab\u0631\u0627\u0645 \u067e\u0631 \u0646\u0638\u0627\u0645\u064a \u0647\u0648\u0627\u064a\u064a \u0689\u06ab\u0631 \u0631\u0627\u06a9\u06d0\u067c\u064a \u0628\u0631\u06cc\u062f\u0648\u0646\u0647 \u0634\u0648\u064a"},"content":{"rendered":"<p dir=\"RTL\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/swn.af\/pictures\/fileman\/2017_Uploads\/2020\/May\/24\/Bagraaam.jpg\" \/><\/p>\n<p dir=\"RTL\">\u067e\u0647 \u067e\u0631\u0648\u0627\u0646 \u06a9\u06d0 \u0627\u0645\u0646\u06cc\u062a\u064a \u0633\u0631\u0686\u06cc\u0646\u06d0 \u0648\u0627\u064a\u064a\u060c \u062f &laquo;\u062a\u0631\u0647\u06ab\u0631\u0648&raquo; \u0689\u0644\u0648 \u0627\u0693\u0648\u0646\u062f \u06a9\u0633\u0627\u0646\u0648 \u0646\u0646 \u0633\u0647\u0627\u0631 \u06f1\u06f0:\u06f4\u06f0 \u0628\u062c\u06d0 \u06cc\u0627\u062f \u0647\u0648\u0627\u064a\u064a \u0689\u06ab\u0631 \u062a\u0647 \u0646\u0696\u062f\u06d0 \u062f \u06cc\u0648\u0647 \u0645\u0648\u067c\u0631&nbsp;\u067e\u0647 \u0681\u0627\u06cc \u067e\u0631 \u0681\u0627\u06cc \u06a9\u0648\u0644\u0648 \u0633\u0631\u0647 \u062f \u0628\u06ab\u0631\u0627\u0645 \u067e\u0631 \u0646\u0638\u0627\u0645\u064a \u0647\u0648\u0627\u064a\u064a \u0689\u06ab\u0631 \u0631\u0627\u06a9\u06d0\u067c\u064a \u0628\u0631\u06cc\u062f\u0648\u0646\u0647 \u06a9\u0693\u064a \u062f\u064a.<\/p>\n<p dir=\"RTL\">\u062f \u067e\u0631\u0648\u0627\u0646 \u062f \u0647\u0645\u063a\u0696\u06cd \u0645\u0631\u06a9\u0632 \u0642\u0648\u0645\u0627\u0646\u062f\u0627\u0646 \u0627\u0644\u0648\u0632\u06cc \u0627\u062d\u0645\u062f\u064a \u062f \u062f\u063a\u0647 \u062e\u0628\u0631 \u062f \u062a\u0627\u06cc\u06cc\u062f \u062a\u0631\u0685\u0646\u06ab\u060c \u0633\u0644\u0627\u0645&zwnj;\u0648\u0637\u0646\u062f\u0627\u0631 \u062a\u0647 \u0648\u06cc\u0644\u064a \u0686\u06d0 \u0644\u0647 \u06cc\u0627\u062f \u0645\u0648\u067c\u0631 \u0646\u0647 \u062f <span dir=\"LTR\">BM1<\/span> \u062f\u0648\u0647 \u0628\u0631\u06cc\u062f\u0648\u0646\u0647 \u062f \u067e\u0631\u0648\u0627\u0646 \u0647\u0648\u0627\u064a\u064a \u0689\u06ab\u0631 \u067e\u0631 \u0644\u0648\u0631\u064a \u0634\u0648\u064a \u062f\u064a.<\/p>\n<p dir=\"RTL\">\u062f \u0646\u0648\u0645\u0648\u0693\u064a \u067e\u0647 \u0648\u06cc\u0646\u0627\u060c \u06cc\u0627\u062f \u0628\u0631\u06cc\u062f\u0648\u0646\u0647 \u067e\u0647 \u0647\u0648\u0627 \u06a9\u06d0 \u062f \u062f\u0641\u0627\u0639\u064a \u0633\u06d0\u0633\u067c\u0645 \u067e\u0647 \u0648\u0633\u06cc\u0644\u0647 \u062e\u0646\u062b\u0627 \u0634\u0648\u064a \u0627\u0648 \u0645\u0631\u06ab&zwnj;\u0698\u0648\u0628\u0644\u0647 \u0647\u0645 \u0646\u0647 \u0644\u0631\u064a.<\/p>\n<p dir=\"RTL\">\u0647\u063a\u0647 \u0648\u0627\u064a\u064a\u060c \u06cc\u0627\u062f \u0645\u0648\u067c\u0631 \u0644\u0647 \u0628\u0631\u06cc\u062f \u0648\u0631\u0648\u0633\u062a\u0647 \u0627\u0648\u0631 \u0627\u062e\u06cc\u0633\u062a\u06cc \u062f\u06cc.<\/p>\n<p dir=\"RTL\">\u062a\u0631 \u0627\u0648\u0633\u0647 \u06a9\u0648\u0645\u06d0 \u0648\u0633\u0644\u0647&zwnj;\u0648\u0627\u0644\u06d0 \u0689\u0644\u06d0 \u062f \u062f\u063a\u0647 \u0628\u0631\u06cc\u062f \u0645\u0633\u0648\u0648\u0644\u06cc\u062a \u067e\u0631 \u063a\u0627\u0693\u0647 \u0646\u0647 \u062f\u06cc \u0627\u062e\u06cc\u0633\u062a\u06cc\u060c \u062e\u0648 \u062f \u067e\u0631\u0648\u0627\u0646 \u0627\u0645\u0646\u06cc\u062a\u064a \u0645\u0633\u0648\u0648\u0644\u0627\u0646 \u0648\u0627\u064a\u064a\u060c \u069a\u0627\u064a\u064a \u062f\u063a\u0647 \u0628\u0631\u06cc\u062f\u0648\u0646\u0647 \u062f \u062f\u0627\u0639\u0634 \u0648\u0633\u0644\u0647&zwnj;\u0648\u0627\u0644\u06d0 \u0689\u0644\u06d0 \u0644\u0647 \u0644\u0648\u0631\u064a \u0634\u0648\u064a \u0648\u064a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u067e\u0647 \u067e\u0631\u0648\u0627\u0646 \u06a9\u06d0 \u0627\u0645\u0646\u06cc\u062a\u064a \u0633\u0631\u0686\u06cc\u0646\u06d0 \u0648\u0627\u064a\u064a\u060c \u062f \u00ab\u062a\u0631\u0647\u06ab\u0631\u0648\u00bb \u0689\u0644\u0648 \u0627\u0693\u0648\u0646\u062f \u06a9\u0633\u0627\u0646\u0648 \u0646\u0646 \u0633\u0647\u0627\u0631 \u06f1\u06f0:\u06f4\u06f0 \u0628\u062c\u06d0 \u062f \u06cc\u0648\u0647 \u062a\u06d0\u0632 \u0631\u0641\u062a\u0627\u0631\u0647 \u0645\u0648\u067c\u0631 \u067e\u0647 \u0681\u0627\u06cc \u067e\u0631 \u0681\u0627\u06cc \u06a9\u0648\u0644\u0648 \u0633\u0631\u0647 \u062f \u0628\u06ab\u0631\u0627\u0645 \u067e\u0631 \u0646\u0638\u0627\u0645\u064a \u0647\u0648\u0627\u064a\u064a \u0689\u06ab\u0631 \u0631\u0627\u06a9\u06d0\u067c\u064a \u0628\u0631\u06cc\u062f\u0648\u0646\u0647 \u06a9\u0693\u064a \u062f\u064a.<\/p>\n","protected":false},"author":1,"featured_media":43231,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[59],"class_list":["post-37267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-31","tag-pashto"],"_links":{"self":[{"href":"https:\/\/swn.af\/archive\/wp-json\/wp\/v2\/posts\/37267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swn.af\/archive\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swn.af\/archive\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swn.af\/archive\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/swn.af\/archive\/wp-json\/wp\/v2\/comments?post=37267"}],"version-history":[{"count":0,"href":"https:\/\/swn.af\/archive\/wp-json\/wp\/v2\/posts\/37267\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swn.af\/archive\/wp-json\/wp\/v2\/media\/43231"}],"wp:attachment":[{"href":"https:\/\/swn.af\/archive\/wp-json\/wp\/v2\/media?parent=37267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swn.af\/archive\/wp-json\/wp\/v2\/categories?post=37267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swn.af\/archive\/wp-json\/wp\/v2\/tags?post=37267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}